{"id":14790,"date":"2026-04-10T08:49:09","date_gmt":"2026-04-10T06:49:09","guid":{"rendered":"https:\/\/bebartlet.com\/?p=14790"},"modified":"2026-04-19T10:22:51","modified_gmt":"2026-04-19T08:22:51","slug":"the-european-pulse-de-politico-y-bebartlet-7000-encuestas-en-6-estados-de-la-union-europea-para-analizar-la-opinion-ciudadana-sobre-defensa-movilidad-energia-innovacion-o-desigualdad","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/the-european-pulse-de-politico-y-bebartlet-7000-encuestas-en-6-estados-de-la-union-europea-para-analizar-la-opinion-ciudadana-sobre-defensa-movilidad-energia-innovacion-o-desigualdad\/","title":{"rendered":"The European Pulse de POLITICO y beBartlet: 7000 encuestas en 6 Estados de la Uni\u00f3n Europea para analizar la opini\u00f3n ciudadana"},"content":{"rendered":"<p><b>The European Pulse de POLITICO y beBartlet: 7000 encuestas en 6 Estados de la Uni\u00f3n Europea para analizar la opini\u00f3n ciudadana sobre defensa, movilidad, energ\u00eda, innovaci\u00f3n o desigualdad. <a href=\"http:\/\/bebartlet.com\/european-pulse-forum-2026\">Accede al an\u00e1lisis completo<\/a>.<\/b><\/p>\n<p>The European Pulse de POLITICO y beBartlet analiza una muestra representativa de la <b>opini\u00f3n de dos terceras partes de los ciudadanos europeos<\/b> impulsando el di\u00e1logo entre la ciudadan\u00eda y las instituciones y empresas de la Uni\u00f3n.<\/p>\n<p>POLITICO y beBartlet <b>presentan hoy los resultados en Barcelona en una cumbre de alto nivel con la participaci\u00f3n<\/b> de Teresa Ribera y St\u00e9phane Sejourn\u00e9e, vicepresidentes de la Comisi\u00f3n Europea, el presidente del Gobierno Pedro S\u00e1nchez, el presidente del Partido Popular espa\u00f1ol Alberto N\u00fa\u00f1ez Feij\u00f3o y un grupo de <b>40 ponentes nacionales a internacionales, eurodiputados, primeros ministros, ministros y representantes institucionales de 10 nacionalidades<\/b> de la Uni\u00f3n Europea y Estados Unidos.<\/p>\n<p>POLITICO y beBartlet han impulsado una <b>innovadora iniciativa combinando la conversaci\u00f3n entre l\u00edderes institucionales de relevancia internacional <\/b>como Teresa Ribera y St\u00e9phane Sejourn\u00e9e, vicepresidentes de la Comisi\u00f3n Europea, as\u00ed como el presidente del Gobierno Pedro S\u00e1nchez, el presidente del Partido Popular espa\u00f1ol Alberto N\u00fa\u00f1ez Feij\u00f3o o representantes institucionales de pa\u00edses como Ucrania, Estados Unidos, Montenegro o Italia, <b>y el an\u00e1lisis de la opini\u00f3n p\u00fablica europea sobre las principales cuestiones de la agenda econ\u00f3mico y social<\/b>. \u201cLideramos desde el conocimiento para tender puentes entre la ciudadan\u00eda y las altas instituciones y sus empresas\u201d, ha se\u00f1alado Adrian Jofre Bosch, socio y presidente de beBartlet.<\/p>\n<p>The European Pulse de POLITICO y beBartlet se basa en <b>6.698 encuestas<\/b> en seis pa\u00edses europeos: Alemania, Francia, Italia, Espa\u00f1a, Polonia y B\u00e9lgica, realizadas entre el <b>13 y el 21 de marzo de 2026<\/b>. Sus resultados se han compartido esta ma\u00f1ana en Barcelona en una cumbre de alto nivel que ha puesto el foco internacional en Espa\u00f1a en un momento determinante para el mundo.<\/p>\n<p>Entre las principales conclusiones del estudio destaca que s\u00f3lo el 21% de los europeos cree que la Uni\u00f3n Europea va en la direcci\u00f3n correcta. Asimismo, el informe panaeuropeo destaca que la guerra en Oriente Pr\u00f3ximo y sus consecuencias, o las pol\u00edticas del presidente de Estados Unidos, Donald Trump, son las principales preocupaciones de los europeos. En este sentido, Espa\u00f1a lidera el enfriamiento con Washington: <b>el <\/b><b>67,4% de los espa\u00f1oles ya ve a EE.UU. como competidor o amenaza, frente al 59,9% del agregado europeo<\/b>.<\/p>\n<p>Respecto a la autosuficiencia energ\u00e9tica europea, el informe evidencia que Espa\u00f1a es de los pa\u00edses m\u00e1s rotundos en el mandato de la autonom\u00eda europea: <b>el 94,1% quiere una Europa m\u00e1s autosuficiente, y hasta el 96,7% respalda producir m\u00e1s energ\u00eda propia<\/b> incluso si sale m\u00e1s caro. Adem\u00e1s, <b>el 81% de los europeos teme que el conflicto con Ir\u00e1n eleve su factura energ\u00e9tica<\/b>, y en Espa\u00f1a la cifra sube al 89,7%.<\/p>\n<p>Por \u00faltimo, el 86,3% de los europeos respalda que Europa desarrolle su propia capacidad de defensa y el 69,5% apoya una fuerza militar europea. En Espa\u00f1a, el apoyo al ej\u00e9rcito europeo sube al 77,3%, pero es el \u00fanico pa\u00eds donde la mayor\u00eda rechaza el servicio militar o civil obligatorio.<\/p>\n<p><b>Energ\u00eda, vivienda y administraciones<\/b><\/p>\n<p>M\u00e1s all\u00e1 del conflicto en Ir\u00e1n y los precios de la energ\u00eda, Europa se enfrenta a otros retos, tambi\u00e9n visibles en los resultados del European Pulse de POLITICO y beBartlet. Sobre la <b>prohibici\u00f3n de la venta de coches de gasolina y di\u00e9sel en 2035<\/b>, el 58,3% de los europeos la rechaza, pero el 65,2% apoya invertir m\u00e1s en transporte p\u00fablico; de su lado, <b>en Espa\u00f1a, el 59,4% rechaza el veto y el 68,1% apoya la inversi\u00f3n<\/b>.<\/p>\n<p>La vivienda es uno de los principales retos sociales, sobretodo en Espa\u00f1a, algo que se evidencia en la encuesta: <b>en el conjunto de la UE, el 49,7% prioriza m\u00e1s vivienda p\u00fablica y social; en Espa\u00f1a, la cifra se dispara al 66,9%<\/b>, la m\u00e1s alta del estudio.<\/p>\n<p>La IA es otra de las preocupaciones de futuro, aunque en este caso hay una clara segmentaci\u00f3n: en la UE, el 50,1% ve m\u00e1s beneficios y el 49,9% m\u00e1s riesgos; aunque <b>Espa\u00f1a es el pa\u00eds m\u00e1s optimista<\/b>, siendo el 62,7% la proporci\u00f3n de poblaci\u00f3n que m\u00e1s beneficios le ve a la IA. Aun as\u00ed, <b>solo el 43,2% conf\u00eda en las tecnol\u00f3gicas europeas para gestionar sus datos.<\/b><\/p>\n<p><b>\u00a0<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The European Pulse de POLITICO y beBartlet: 7000 encuestas en 6 Estados de la Uni\u00f3n Europea para analizar la opini\u00f3n ciudadana sobre defensa, movilidad, energ\u00eda, innovaci\u00f3n o desigualdad. Accede al an\u00e1lisis completo. The European Pulse de POLITICO y beBartlet analiza una muestra representativa de la opini\u00f3n de dos terceras partes de los ciudadanos europeos impulsando [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":14937,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-14790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bebartlet"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/14790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=14790"}],"version-history":[{"count":30,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/14790\/revisions"}],"predecessor-version":[{"id":14909,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/14790\/revisions\/14909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/14937"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=14790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=14790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=14790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}