{"id":16492,"date":"2025-03-10T07:16:56","date_gmt":"2025-03-10T06:16:56","guid":{"rendered":"https:\/\/bebartlet.com\/bebartlet-y-trivu-impulsamos-el-foro-next-gen-el-davos-de-las-generaciones-millennial-y-zeta\/"},"modified":"2025-03-10T07:16:56","modified_gmt":"2025-03-10T06:16:56","slug":"bebartlet-y-trivu-impulsamos-el-foro-next-gen-el-davos-de-las-generaciones-millennial-y-zeta","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/bebartlet-y-trivu-impulsamos-el-foro-next-gen-el-davos-de-las-generaciones-millennial-y-zeta\/","title":{"rendered":"Impulsamos\u00a0el Foro Next Gen, el \u2018Davos\u2019 de las generaciones Millennial y Zeta"},"content":{"rendered":"<p><strong>beBartlet y TRIVU<\/strong>, las dos empresas de referencia generacional en Espa\u00f1a,\u00a0<strong>nos unimos para impulsar el Foro Next Gen<\/strong>, el <strong>primer \u2018Davos\u2019 de las generaciones Millennial y Zeta de nuestro pa\u00eds que estar\u00e1 protagonizado por los principales l\u00edderes econ\u00f3micos, sociales e institucionales de las generaciones nacidas en democracia.<\/strong> El Foro, de car\u00e1cter anual, aspira a consolidarse como el espacio de referencia generacional para construir mejores escenarios para el siglo XXI. Con esta alianza, TRIVU, el mayor ecosistema de talento de Espa\u00f1a, y beBartlet, el primer gabinete de incidencia p\u00fablica de nuestro pa\u00eds, <strong>compartimos la ambici\u00f3n de contribuir a generar las condiciones para abordar conjuntamente los grandes retos de las pr\u00f3ximas d\u00e9cadas con quienes liderar\u00e1n las instituciones y las empresas en los pr\u00f3ximos a\u00f1os.\u00a0<\/strong><\/p>\n<p><strong>\u201cInspirado en la ambici\u00f3n del Foro Econ\u00f3mico Mundial de Davos,<\/strong> que tiene como fin fomentar la cooperaci\u00f3n entre los referentes econ\u00f3micos y sociales para buscar soluciones conjuntas a problemas globales,<strong> el Foro Next Gen recrear\u00e1 esta din\u00e1mica para fomentar alianzas y construir el futuro por quienes ser\u00e1n sus protagonistas\u201d, explica Pablo Gonz\u00e1lez Ruiz de la Torre,<\/strong> Fundador de TRIVU. Para <strong>Nacho Corredor,<\/strong> socio y vicepresidente de beBartlet, \u201cel Foro Next Gen se convertir\u00e1 en la jornada de trabajo anual de referencia de las generaciones nacidas en democracia, donde<strong> sus principales l\u00edderes anticipen escenarios y generen las condiciones de colaboraci\u00f3n necesarias para impulsar las grandes transformaciones\u201d.<\/strong> \u201cLa transformaci\u00f3n de Espa\u00f1a est\u00e1 en manos de las generaciones Millennial y Zeta y merecemos todo el protagonismo\u201d, concluye.<\/p>\n<p><strong>La iniciativa impulsada de la mano de Gonz\u00e1lez Ruiz de la Torre<\/strong> (Forbes30under30 y miembro del Consejo Asesor de la Fundaci\u00f3n Princesa de Girona), y <strong>Corredor<\/strong> (miembro del consejo asesor en Madrid de la Societat Barcelonesa d&#8217;Estudis Economics i Socials y miembro del C\u00edrculo Reina de la Fundaci\u00f3n Museo Reina Sof\u00eda), <strong>pone el foco en las nuevas generaciones de empresarios, artistas, pol\u00edticos y otros referentes de la sociedad que construir\u00e1n la Espa\u00f1a de los pr\u00f3ximos a\u00f1os<\/strong>. El Foro Next Gen, que organizar\u00e1 su primera edici\u00f3n a finales de a\u00f1o, <strong>contar\u00e1 con la presencia de los principales l\u00edderes institucionales y empresariales espa\u00f1oles nacidos a partir de 1980 e impulsar\u00e1 un debate p\u00fablico que contribuya a la transformaci\u00f3n de Espa\u00f1a desde la pluralidad y transversalidad econ\u00f3mica y social.\u00a0<\/strong><\/p>\n<p><strong>\u201cEn un contexto global marcado por la incertidumbre y el cambio constante, es necesario contar desde ya con los liderazgos emergentes como protagonistas de las nuevas soluciones<\/strong>\u201d, declara Corredor. \u00a0\u201c<strong>No existe en Espa\u00f1a un Foro por y para nuestra generaci\u00f3n que ya est\u00e1 asumiendo las principales posiciones de liderazgo<\/strong> en el \u00e1mbito empresarial, pol\u00edtico, medi\u00e1tico o social\u201d, concluye Ruiz de la Torre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>beBartlet y TRIVU, las dos empresas de referencia generacional en Espa\u00f1a,\u00a0nos unimos para impulsar el Foro Next Gen, el primer \u2018Davos\u2019 de las generaciones Millennial y Zeta de nuestro pa\u00eds que estar\u00e1 protagonizado por los principales l\u00edderes econ\u00f3micos, sociales e institucionales de las generaciones nacidas en democracia. El Foro, de car\u00e1cter anual, aspira a consolidarse [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1115],"tags":[1157,1156,1332],"class_list":["post-16492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bebartlet-pt","tag-bebartlet","tag-incidencia-publica","tag-trivu"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16492"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16493"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}