{"id":16505,"date":"2025-01-29T09:29:26","date_gmt":"2025-01-29T08:29:26","guid":{"rendered":"https:\/\/bebartlet.com\/mas-de-una-treintena-de-expertos-y-politicos-de-los-principales-partidos-nos-hemos-juntado-una-vez-mas-para-construir-soluciones-en-el-ambito-de-la-vivienda\/"},"modified":"2025-01-29T09:29:26","modified_gmt":"2025-01-29T08:29:26","slug":"mas-de-una-treintena-de-expertos-y-politicos-de-los-principales-partidos-nos-hemos-juntado-una-vez-mas-para-construir-soluciones-en-el-ambito-de-la-vivienda","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/mas-de-una-treintena-de-expertos-y-politicos-de-los-principales-partidos-nos-hemos-juntado-una-vez-mas-para-construir-soluciones-en-el-ambito-de-la-vivienda\/","title":{"rendered":"M\u00e1s de una treintena de expertos y pol\u00edticos de los principales partidos nos hemos juntado (una vez m\u00e1s) para construir soluciones en el \u00e1mbito de la vivienda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16505\" class=\"elementor elementor-16505 elementor-11781\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a78a9a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a78a9a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d40b74b\" data-id=\"3d40b74b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe475ce elementor-widget elementor-widget-video\" data-id=\"fe475ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/dQGZUq3z_9Y&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72bf803a elementor-widget elementor-widget-text-editor\" data-id=\"72bf803a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"font-weight: 400;\">M\u00e1s de una treintena de expertos y pol\u00edticos de los principales partidos nos hemos juntado (una vez m\u00e1s) para construir soluciones en el \u00e1mbito de la vivienda.<\/span>\r\n\r\n\ud83d\udde3\ufe0f <strong>Alexandra Delgado<\/strong> (doctora en urbanismo e investigadora principal de Arquitectura) \u201cLa reducida eficiencia energ\u00e9tica del parque edificatorio residencial<strong> supone un desaf\u00edo para la sociedad y la econom\u00eda espa\u00f1ola\u201d.<\/strong>\r\n\r\n\ud83d\udde3\ufe0f Mar\u00eda Jos\u00e9 Picchio-Marchetti (<strong>Directora General de Vivienda y Rehabilitaci\u00f3n de la Comunidad de Madrid<\/strong>):<strong> \u201cFomentar las hipotecas o \u2018bonos verdes\u2019<\/strong> con diferenciales m\u00e1s atractivos puede ser <strong>una v\u00eda eficaz para incentivar la compra o la rehabilitaci\u00f3n de viviendas m\u00e1s sostenibles\u201d. <\/strong>\r\n\r\n\ud83d\udde3\ufe0f Rafaela Romero: (Diputada del PSOE y<strong> Vicepresidenta de la Comisi\u00f3n de Vivienda y Agenda Urbana en el Congreso<\/strong>) \u201c<strong>Implementar programas para colectivos vulnerables aumenta la eficacia para disminuir la pobreza energ\u00e9tica&#8221;.<\/strong>\r\n\r\n\ud83d\udde3\ufe0f <strong>Ram\u00f3n Mateo<\/strong> (Socio y director de An\u00e1lisis e Impacto Regulatorio de beBartlet): \u201c<strong>La transici\u00f3n verde en el sector residencial es una pol\u00edtica prioritaria<\/strong> en la que la mejora de la eficiencia energ\u00e9tica es una herramienta imprescindible\u201d.\r\n\r\n#Misi\u00f3n_bB Contrato Social es una iniciativa de beBartlet con el apoyo de ING\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>https:\/\/youtu.be\/dQGZUq3z_9YM\u00e1s de una treintena de expertos y pol\u00edticos de los principales partidos nos hemos juntado (una vez m\u00e1s) para construir soluciones en el \u00e1mbito de la vivienda. \ud83d\udde3\ufe0f Alexandra Delgado (doctora en urbanismo e investigadora principal de Arquitectura) \u201cLa reducida eficiencia energ\u00e9tica del parque edificatorio residencial supone un desaf\u00edo para la sociedad y la econom\u00eda [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16506,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1131,1115],"tags":[],"class_list":["post-16505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missaobebartlet","category-bebartlet-pt"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16505"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16506"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}