{"id":16522,"date":"2024-12-10T05:59:14","date_gmt":"2024-12-10T04:59:14","guid":{"rendered":"https:\/\/bebartlet.com\/el-primer-proceso-de-escucha-activa-de-la-movilidad-urbana-en-espana\/"},"modified":"2024-12-10T05:59:14","modified_gmt":"2024-12-10T04:59:14","slug":"el-primer-proceso-de-escucha-activa-de-la-movilidad-urbana-en-espana","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/el-primer-proceso-de-escucha-activa-de-la-movilidad-urbana-en-espana\/","title":{"rendered":"El primer proceso de escucha activa de la movilidad urbana en Espa\u00f1a"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16522\" class=\"elementor elementor-16522 elementor-11240\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-509de09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"509de09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f699d68\" data-id=\"f699d68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2f6141 elementor-widget elementor-widget-text-editor\" data-id=\"a2f6141\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante m\u00e1s de un a\u00f1o, hemos sumado las distintas visiones de un centenar de l\u00edderes institucionales y expertos sectoriales en Madrid y Barcelona para abordar\u00a0<span style=\"font-weight: bold;\">la transformaci\u00f3n de la movilidad urbana.\u00a0<\/span>Porque\u00a0avanzar hacia una movilidad urbana m\u00e1s sostenible, segura y conectada s\u00f3lo es posible desde el consenso y la colaboraci\u00f3n de todos los actores implicados.\u00a0\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d957c7e elementor-widget elementor-widget-video\" data-id=\"d957c7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/5hHNVvNV22w?si=CfSMEdWDlcH0TIgK&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f668b85 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f668b85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63d84080\" data-id=\"63d84080\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-229fc3d elementor-widget elementor-widget-text-editor\" data-id=\"229fc3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Hoy, <\/span><b>Josep Mar\u00eda Fortuny,<\/b><span style=\"font-weight: 400;\"> uno de los mayores<\/span><b> expertos en movilidad de nuestro pa\u00eds<\/b><span style=\"font-weight: 400;\">, <a href=\"https:\/\/agendapublica.es\/noticia\/19504\/las-diez-propuestas-que-transformarian-la-movilidad-urbana\" target=\"_blank\" rel=\"noopener\">propone diez medidas<\/a><\/span><b>\u00a0<\/b><span style=\"font-weight: 400;\">que transformar\u00edan la movilidad urbana en Espa\u00f1a y que son el punto de partida de un nuevo enfoque en las pol\u00edticas p\u00fablicas de movilidad.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">En 2025, seguiremos con la Misi\u00f3n Movilidad.\u00a0<\/span><\/p><p><strong>Misi\u00f3n Movilidad es el primer proceso de escucha activa de la movilidad urbana, <\/strong><span style=\"font-weight: 400;\">una iniciativa de <strong>beBartlet<\/strong> con el apoyo de Cabify. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Durante m\u00e1s de un a\u00f1o, hemos sumado las distintas visiones de un centenar de l\u00edderes institucionales y expertos sectoriales en Madrid y Barcelona para abordar\u00a0la transformaci\u00f3n de la movilidad urbana.\u00a0Porque\u00a0avanzar hacia una movilidad urbana m\u00e1s sostenible, segura y conectada s\u00f3lo es posible desde el consenso y la colaboraci\u00f3n de todos los actores implicados.\u00a0\u00a0 https:\/\/youtu.be\/5hHNVvNV22w?si=CfSMEdWDlcH0TIgK Hoy, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1115,1131],"tags":[],"class_list":["post-16522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bebartlet-pt","category-missaobebartlet"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16522"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16523"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}