{"id":16558,"date":"2024-07-17T08:14:55","date_gmt":"2024-07-17T06:14:55","guid":{"rendered":"https:\/\/bebartlet.com\/alejandro-labanda-bebartlet-en-20-minutos-es-urgente-que-nuevas-figuras-puedan-aportar-flexibilidad-al-sistema-y-facilitar-la-integracion-de-renovables\/"},"modified":"2024-07-17T08:14:55","modified_gmt":"2024-07-17T06:14:55","slug":"alejandro-labanda-bebartlet-en-20-minutos-es-urgente-que-nuevas-figuras-puedan-aportar-flexibilidad-al-sistema-y-facilitar-la-integracion-de-renovables","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/alejandro-labanda-bebartlet-en-20-minutos-es-urgente-que-nuevas-figuras-puedan-aportar-flexibilidad-al-sistema-y-facilitar-la-integracion-de-renovables\/","title":{"rendered":"Alejandro Labanda (beBartlet), en 20 Minutos: &#8220;Es urgente que nuevas figuras puedan aportar flexibilidad al sistema y facilitar la integraci\u00f3n de renovables&#8221;"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16558\" class=\"elementor elementor-16558 elementor-10590\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fc87dcf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fc87dcf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73b78993\" data-id=\"73b78993\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42eb7de6 elementor-widget elementor-widget-text-editor\" data-id=\"42eb7de6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlejandro Labanda (director de Transici\u00f3n Ecol\u00f3gica de beBartlet), es entrevistado en 20 Minutos para analizar la participaci\u00f3n de nuevos actores en el mercado el\u00e9ctrico en transposici\u00f3n de la Directiva 2019\/944 de mercado interior.\r\n\r\n&nbsp;\r\n\r\n&#8220;Es urgente que nuevas figuras, como el agregador independiente o los mercados locales, puedan aportar flexibilidad al sistema y facilitar la integraci\u00f3n de renovables&#8221;, agrega.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71e871a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71e871a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1a6108\" data-id=\"d1a6108\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2de3025 elementor-widget elementor-widget-button\" data-id=\"2de3025\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.20minutos.es\/lainformacion\/economia-y-finanzas\/cnmc-refinanciar-servicios-ajuste-factura-luz-crecen-cada-vez-mas-5531775\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver noticia<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Alejandro Labanda (director de Transici\u00f3n Ecol\u00f3gica de beBartlet), es entrevistado en 20 Minutos para analizar la participaci\u00f3n de nuevos actores en el mercado el\u00e9ctrico en transposici\u00f3n de la Directiva 2019\/944 de mercado interior. &nbsp; &#8220;Es urgente que nuevas figuras, como el agregador independiente o los mercados locales, puedan aportar flexibilidad al sistema y facilitar la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1117,1132],"tags":[1342,1156],"class_list":["post-16558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa-pt","category-20minutos-es-pt","tag-alejandro-labanda","tag-incidencia-publica"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16558"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16559"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}