{"id":16562,"date":"2024-07-08T08:33:06","date_gmt":"2024-07-08T06:33:06","guid":{"rendered":"https:\/\/bebartlet.com\/la-colaboracion-publico-privada-como-eje-transformador-de-las-ciudades\/"},"modified":"2024-07-08T08:33:06","modified_gmt":"2024-07-08T06:33:06","slug":"la-colaboracion-publico-privada-como-eje-transformador-de-las-ciudades","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/la-colaboracion-publico-privada-como-eje-transformador-de-las-ciudades\/","title":{"rendered":"La colaboraci\u00f3n p\u00fablico-privada como eje transformador de las ciudades"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16562\" class=\"elementor elementor-16562 elementor-10136\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7acf9e5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7acf9e5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14be48e0\" data-id=\"14be48e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d10fd14 elementor-widget elementor-widget-text-editor\" data-id=\"4d10fd14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\ud83d\udde3\ufe0f <strong>Concepci\u00f3n Campos Acu\u00f1a<\/strong> (experta en gesti\u00f3n p\u00fablica): \u201c<strong>Tenemos que generar espacios de confianza entre el sector p\u00fablico y el sector privado<\/strong> para poder aprovechar las oportunidades que presenta la colaboraci\u00f3n p\u00fablico-privada y mitigar los riesgos que, como en toda gesti\u00f3n, existen\u201d.\n\n\ud83e\udd1d <strong>Javier \u00dabeda<\/strong> (alcalde de Boadilla del Monte): \u201cHemos compartido reflexiones y hemos visto que es imprescindible, independientemente de la orientaci\u00f3n ideol\u00f3gica, que todos trabajamos en esa l\u00ednea\u201d.\n\n\ud83d\udd1d<strong>\u00c1ngeles Armis\u00e9n<\/strong> (Presidenta de la Diputaci\u00f3n de Palencia): \u201cLa colaboraci\u00f3n p\u00fablico-privada no es s\u00f3lo la que define la ley. Es la colaboraci\u00f3n con nuestra propia sociedad\u201d.\n\n\ud83d\udd1b <strong>Sole Murillo<\/strong> (concejala del Ayuntamiento de Madrid): \u201cSi la administraci\u00f3n es capaz de aprender de los procesos \u00e1giles, operativos y pr\u00e1cticos de la empresa, entonces ser\u00e1 un gana-gana entre empresa y administraci\u00f3n\u201d.\n\n\ud83d\ude4c <strong>Eduard Rivas <\/strong>(alcalde de Esparraguera y presidente de la Federaci\u00f3n de Municipios de Catalunya): \u201cHa sido un momento para reflexionar sobre el mundo local, hacia d\u00f3nde vamos, y sobre todo en este caso, hacia qu\u00e9 l\u00f3gica de colaboraci\u00f3n podemos tener entre el mundo p\u00fablico y privado, en una l\u00f3gica de generar bienestar para la ciudadan\u00eda, para nuestros vecinos&#8221;.\n\n#Mision_bB Ciudades es una iniciativa de beBartlet con la colaboraci\u00f3n del Observatorio Local y el apoyo de Fundaci\u00f3n &#8216;la Caixa&#8217;.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d599637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d599637\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60919e9\" data-id=\"60919e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-943f7cf elementor-widget elementor-widget-video\" data-id=\"943f7cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=wYeyBUe4eok&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\ud83d\udde3\ufe0f Concepci\u00f3n Campos Acu\u00f1a (experta en gesti\u00f3n p\u00fablica): \u201cTenemos que generar espacios de confianza entre el sector p\u00fablico y el sector privado para poder aprovechar las oportunidades que presenta la colaboraci\u00f3n p\u00fablico-privada y mitigar los riesgos que, como en toda gesti\u00f3n, existen\u201d. \ud83e\udd1d Javier \u00dabeda (alcalde de Boadilla del Monte): \u201cHemos compartido reflexiones y hemos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16563,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1115,1131],"tags":[1348,1349,1156,1350],"class_list":["post-16562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bebartlet-pt","category-missaobebartlet","tag-alcaldes","tag-colaboracion-publico-privada","tag-incidencia-publica","tag-mision-bebartlet"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16562"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16563"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}