{"id":16594,"date":"2024-04-05T14:46:20","date_gmt":"2024-04-05T12:46:20","guid":{"rendered":"https:\/\/bebartlet.com\/9703\/"},"modified":"2024-04-05T14:46:20","modified_gmt":"2024-04-05T12:46:20","slug":"9703","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/9703\/","title":{"rendered":"La competitividad de las empresas espa\u00f1olas est\u00e1 en juego"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16594\" class=\"elementor elementor-16594 elementor-9703\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a299c6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a299c6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26aa19a3\" data-id=\"26aa19a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-418a1b6c elementor-widget elementor-widget-text-editor\" data-id=\"418a1b6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"feed-shared-update-v2__description-wrapper mr2\" tabindex=\"-1\">\r\n<div class=\"feed-shared-inline-show-more-text feed-shared-update-v2__description feed-shared-inline-show-more-text--minimal-padding feed-shared-inline-show-more-text--3-lines feed-shared-inline-show-more-text--expanded \" tabindex=\"-1\" data-artdeco-is-focused=\"true\">\r\n<div class=\"update-components-text relative update-components-update-v2__commentary \" dir=\"ltr\">\r\n\r\n<span class=\"break-words \"><span dir=\"ltr\">Este viernes, la Oficina del Parlamento Europeo en Espa\u00f1a ha acogido <strong>una nueva sesi\u00f3n de la Misi\u00f3n beBartlet con el apoyo del Foro de Marcas Renombradas Espa\u00f1olas.<\/strong><\/span><\/span>\r\n\r\n<strong>Pablo L\u00f3pez Gil<\/strong> (Director General del Foro de Marcas Renombradas Espa\u00f1olas), <strong>destacaba que en esta Misi\u00f3n<\/strong><strong>se <\/strong><span style=\"font-weight: 400;\"><strong>&#8220;ha analizado<\/strong> desde la perspectiva de las propias empresas como desde la perspectiva de <strong>qu\u00e9 puede hacer el regulador, las instituciones y la administraci\u00f3n por favorecer una mayor competitividad&#8221;<\/strong>. Mientras, <strong>Enma L\u00f3pez (<\/strong>Portavoz Adjunta del PSOE en el Ayuntamiento de Madrid) <strong>indicaba que \u201ctenemos<\/strong> un reto como pa\u00eds <strong>que es cre\u00e9rnoslo y ser conscientes<\/strong> del gran papel al que est\u00e1n jugando muchas de las empresas espa\u00f1olas&#8221;.<\/span>\r\n\r\n<\/div>\r\n<div dir=\"ltr\"><\/div>\r\n<div class=\"update-components-text relative update-components-update-v2__commentary \" dir=\"ltr\"><span class=\"break-words \"><span dir=\"ltr\"><span style=\"font-weight: 400;\">En cambio,<\/span> <strong>Alberto Oliver<\/strong> (Portavoz de Hacienda de M\u00e1s Madrid en la Asamblea de Madrid), se\u00f1alaba la educaci\u00f3n y el tama\u00f1o de la educaci\u00f3n como elementos esenciales: <span style=\"font-weight: 400;\">\u201cTenemos que ser capaces de incrementar el tama\u00f1o de las empresas y tenemos que invertir m\u00e1s en educaci\u00f3n y dar ese plus que nos permitir\u00e1 abordar los retosde futuro&#8221;<\/span><\/span><\/span><\/div>\r\n<div dir=\"ltr\"><\/div>\r\n<div class=\"update-components-text relative update-components-update-v2__commentary \" dir=\"ltr\"><span class=\"break-words \"><span dir=\"ltr\">Un asunto, el del tama\u00f1o de las empresas, al que tambi\u00e9n se refer\u00eda<strong>\u00a0Irene Garrido Valenzuela<\/strong> (vicepresidenta de la Comisi\u00f3n de Industria y Turismo en el Congreso y secretaria de Estado de Econom\u00eda entre 2016 y 2019):\u00a0&#8220;E<span style=\"font-weight: 400;\">s necesario que crezcan y se regule para favorecer el crecimiento empresarial\u201d<\/span><\/span><\/span><\/div>\r\n<\/div>\r\n<div dir=\"ltr\"><\/div>\r\n<div dir=\"ltr\"><span class=\"break-words \"><span dir=\"ltr\">En este sentido, <strong>Mario Lara<\/strong> (Director de ESADE), <strong>apuntaba que <\/strong><span style=\"font-weight: 400;\"><strong>\u201cla soluci\u00f3n a los retos pasa necesariamente por reforzar la colaboraci\u00f3n p\u00fablico privada y las administraciones<\/strong> tienen que desarrollar marcos regulatorios m\u00e1s sencillos&#8221;.<\/span><\/span><\/span><\/div>\r\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-930d0a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"930d0a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c19da00\" data-id=\"c19da00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34a82a9 elementor-widget elementor-widget-video\" data-id=\"34a82a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=DTQhXh4uN_g&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Este viernes, la Oficina del Parlamento Europeo en Espa\u00f1a ha acogido una nueva sesi\u00f3n de la Misi\u00f3n beBartlet con el apoyo del Foro de Marcas Renombradas Espa\u00f1olas. Pablo L\u00f3pez Gil (Director General del Foro de Marcas Renombradas Espa\u00f1olas), destacaba que en esta Misi\u00f3nse &#8220;ha analizado desde la perspectiva de las propias empresas como desde la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16595,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1115,1131],"tags":[1368,1274,1338,1350],"class_list":["post-16594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bebartlet-pt","category-missaobebartlet","tag-competitividad","tag-economia","tag-empresas","tag-mision-bebartlet"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16594"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16595"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}