{"id":16639,"date":"2023-11-17T08:27:41","date_gmt":"2023-11-17T07:27:41","guid":{"rendered":"https:\/\/bebartlet.com\/el-poder-de-la-influencia\/"},"modified":"2023-11-17T08:27:41","modified_gmt":"2023-11-17T07:27:41","slug":"el-poder-de-la-influencia","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/el-poder-de-la-influencia\/","title":{"rendered":"El poder de la influencia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16639\" class=\"elementor elementor-16639 elementor-8550\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70066a23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70066a23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c4c3f0f\" data-id=\"5c4c3f0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-530a80e1 elementor-widget elementor-widget-text-editor\" data-id=\"530a80e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Adrian Jofre Bosch<\/strong>, socio y presidente de beBartlet, y <strong>Nacho Corredor<\/strong>, socio y presidente del C\u00edrculo de Asesores de beBartlet, <strong>repasan en El Pa\u00eds<\/strong> los primeros a\u00f1os de beBartlet.<\/p><p><strong>Adrian y Nacho <\/strong>se conocieron en 2009 en Barcelona y <strong>hace casi cinco a\u00f1os decidieron<\/strong>, tras unas vacaciones, <strong>iniciar juntos un nuevo camino profesional<\/strong> exportando el modelo de advocacy anglosaj\u00f3n: <strong>la incidencia p\u00fablica.<\/strong> Aunque <strong>beBartlet naci\u00f3 unos d\u00edas antes del inicio de la pandemia<\/strong> y el mundo entr\u00f3 en una etapa de incertidumbres <strong>desde el principio la empresa cont\u00f3 con la confianza de grandes clientes<\/strong> con vocaci\u00f3n de transformaci\u00f3n de Espa\u00f1a.<\/p><p>Tras estos a\u00f1os, y con <strong>un equipo de 25 profesionales<\/strong>, <strong>beBartlet<\/strong> <strong>ha contribuido<\/strong> junto a otras empresas del \u00e1mbito de la comunicaci\u00f3n y los asuntos p\u00fablicos a que en Espa\u00f1a <strong>la ciudadan\u00eda se empodere<\/strong> m\u00e1s ante las instituciones, algunas de <strong>las principales empresas mejoren su capacidad de incidir<\/strong> en las grandes transformaciones y <strong>las instituciones tomen decisiones a partir de procesos m\u00e1s participativos.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4068d03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4068d03\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-905bf41\" data-id=\"905bf41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f7d69b elementor-widget elementor-widget-button\" data-id=\"1f7d69b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver noticia<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Adrian Jofre Bosch, socio y presidente de beBartlet, y Nacho Corredor, socio y presidente del C\u00edrculo de Asesores de beBartlet, repasan en El Pa\u00eds los primeros a\u00f1os de beBartlet. Adrian y Nacho se conocieron en 2009 en Barcelona y hace casi cinco a\u00f1os decidieron, tras unas vacaciones, iniciar juntos un nuevo camino profesional exportando el [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16640,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1117,1143],"tags":[1412,1370,1331,1156,1345],"class_list":["post-16639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa-pt","category-el-pais-pt","tag-adrian-jofre","tag-el-pais","tag-entrevista","tag-incidencia-publica","tag-nacho-corredor"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16639"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16640"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}