{"id":16774,"date":"2022-05-17T07:15:17","date_gmt":"2022-05-17T05:15:17","guid":{"rendered":"https:\/\/bebartlet.com\/bebartlet-greenpeace-primer-dialogo-nuevosliderazgosbb-transicion-ecologica\/"},"modified":"2022-05-17T07:15:17","modified_gmt":"2022-05-17T05:15:17","slug":"bebartlet-greenpeace-primer-dialogo-nuevosliderazgosbb-transicion-ecologica","status":"publish","type":"post","link":"https:\/\/bebartlet.com\/pt-pt\/bebartlet-greenpeace-primer-dialogo-nuevosliderazgosbb-transicion-ecologica\/","title":{"rendered":"beBartlet y Greenpeace impulsamos un espacio entre pol\u00edticos y activistas para superar brechas en la transici\u00f3n ecol\u00f3gica"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16774\" class=\"elementor elementor-16774 elementor-2304\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d3e1fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d3e1fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e14f3bb\" data-id=\"e14f3bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6adce66 elementor-widget elementor-widget-text-editor\" data-id=\"6adce66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hay otra manera de\u00a0<strong>dialogar y debatir\u00a0<\/strong>sobre la\u00a0<strong>emergencia clim\u00e1tica<\/strong>. Una forma que\u00a0<strong>se aleja de la polarizaci\u00f3n<\/strong>\u00a0y que est\u00e1 m\u00e1s\u00a0<strong>cerca de la empat\u00eda<\/strong>. Que no busca el enfrentamiento, sino el\u00a0<strong>di\u00e1logo<\/strong>. Ante el desaf\u00edo de la\u00a0<strong>crisis clim\u00e1tica<\/strong>, necesitamos\u00a0<strong>consenso<\/strong>. Y para ello es vital sentarnos,\u00a0<strong>compartir preocupaciones comunes<\/strong>\u00a0y\u00a0<strong>debatir propuestas\u00a0<\/strong>para abordar juntos este reto.\u00a0<\/p><p>Con esta idea, desde\u00a0<strong><a href=\"https:\/\/bebartlet.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">beBartlet\u00a0<\/a><\/strong>hemos impulsado junto a\u00a0<a href=\"https:\/\/es.greenpeace.org\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Greenpeace\u00a0<\/strong><\/a>el primer encuentro de los\u00a0<strong>nuevos liderazgos pol\u00edticos y sociales en el \u00e1mbito de la Transici\u00f3n ecol\u00f3gica<\/strong>. \u201cEn el\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=_kyg9Ac0w5Q&amp;list=TLGG-xRStwH2cIsxMTAyMjAyMg\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Observatorio de #NuevosLiderazgosbB<\/strong><\/a>\u00a0de beBartlet hemos impulsado una red con los\u00a0<a href=\"https:\/\/bebartlet.com\/nuevosliderazgos\/\" target=\"_blank\" rel=\"noreferrer noopener\">l\u00edderes emergentes<\/a>\u00a0de la pol\u00edtica espa\u00f1ola. La lucha contra el<strong>\u00a0cambio clim\u00e1tico es uno de nuestros principales retos como generaci\u00f3n<\/strong>\u201c, apunta Adrian Jofre Bosch, socio y presidente del gabinete de incidencia p\u00fablica\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=1B1PxGIdjs0\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>beBartlet<\/strong><\/a>.<\/p><p>\u201cDebemos consolidar\u00a0<strong>espacios de interacci\u00f3n<\/strong>\u00a0donde las personas comprometidas con el planeta y que van a<strong>\u00a0tomar decisiones<\/strong>\u00a0las pr\u00f3ximas d\u00e9cadas aborden juntos las\u00a0<strong>pol\u00edticas p\u00fablicas contra el cambio clim\u00e1tico<\/strong>\u201d, se\u00f1ala Eva Salda\u00f1a, directora de Greenpeace Espa\u00f1a.<\/p><p><strong>Muriel Larrea<\/strong>\u00a0(diputada en el parlamento vasco por el PP),\u00a0<strong>Carlos Canino<\/strong>\u00a0(asesor parlamentario en el Congreso de los Diputados por Cs),\u00a0<strong>Joan Groizard\u00a0<\/strong>(director general del IDAE),\u00a0<strong>H\u00e9ctor Tejero<\/strong>\u00a0(diputado auton\u00f3mico de M\u00e1s Madrid) o\u00a0<strong>Alicia Homs<\/strong>\u00a0(eurodiputada socialista)\u00a0fueron algunos de los\u00a0<strong>nuevos liderazgos pol\u00edticos<\/strong>\u00a0protagonistas de la sesi\u00f3n.<\/p><p>Asimismo,\u00a0<strong>Paula Mart\u00ednez\u00a0<\/strong>(Fridays for Future),\u00a0<strong>Sara Acu\u00f1a<\/strong>\u00a0(Ecologistas en Acci\u00f3n),\u00a0<strong>Diego Ferraz<\/strong>\u00a0(ambient\u00f3logo y divulgador) o\u00a0<strong>Laura Reboul<\/strong>\u00a0(Greenpeace) fueron tambi\u00e9n algunos de los\u00a0<strong>l\u00edderes sociales medioambientales<\/strong>\u00a0participantes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fcd297 elementor-widget elementor-widget-video\" data-id=\"8fcd297\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=bjtmrB4nPVQ&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ab3c81 elementor-widget elementor-widget-text-editor\" data-id=\"5ab3c81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el encuentro, moderado por la soci\u00f3loga\u00a0<strong>Cristina Monge<\/strong>\u00a0(<strong>experta en cambio clim\u00e1tico<\/strong>\u00a0y\u00a0<strong>asesora de\u00a0<a href=\"https:\/\/bebartlet.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">beBartlet<\/a><\/strong>), se abordaron cuestiones como el\u00a0<strong>modelo econ\u00f3mico\u00a0<\/strong>y las\u00a0<strong>necesidades de la sociedad\u00a0<\/strong>actual para movilizarse por esta causa. Tambi\u00e9n hubo espacio para intercambiar\u00a0<strong>qu\u00e9 echan de menos cada colectivo del otro\u00a0<\/strong>y encontrar\u00a0<strong>visiones comunes sobre c\u00f3mo abordar estos problemas<\/strong>.<\/p><p>El objetivo de este nuevo espacio es\u00a0<strong>facilitar una conversaci\u00f3n para generar puentes y establecer relaciones de confianza<\/strong>\u00a0entre quienes est\u00e1n llamados a ser los<strong>\u00a0l\u00edderes del futuro<\/strong>\u00a0en el \u00e1mbito de la\u00a0<strong>transici\u00f3n ecol\u00f3gica<\/strong>. En ese contexto se desarroll\u00f3 la jornada del viernes y en un ambiente seguro donde tanto\u00a0<strong>l\u00edderes pol\u00edticos y sociales\u00a0<\/strong>emergentes pudieron\u00a0<strong>expresar propuestas, preocupaciones y alternativas a la emergencia clim\u00e1tica<\/strong>\u00a0que ya estamos viviendo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Desde beBartlet hemos impulsado junto a Greenpeace el primer encuentro de los nuevos liderazgos pol\u00edticos y sociales en el \u00e1mbito de la Transici\u00f3n ecol\u00f3gica.<\/p>\n","protected":false},"author":9,"featured_media":16775,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1131],"tags":[],"class_list":["post-16774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missaobebartlet"],"_links":{"self":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=16774"}],"version-history":[{"count":0,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/16774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media\/16775"}],"wp:attachment":[{"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=16774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=16774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bebartlet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=16774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}